{"id":3507,"date":"2023-01-25T14:57:01","date_gmt":"2023-01-25T17:57:01","guid":{"rendered":"https:\/\/news.contabilit.com.br\/?p=1372"},"modified":"2023-01-25T14:57:01","modified_gmt":"2023-01-25T17:57:01","slug":"veja-as-vantagens-de-comprar-com-cnpj","status":"publish","type":"post","link":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/","title":{"rendered":"Veja as Vantagens de Comprar com CNPJ"},"content":{"rendered":"<p>Ter um cadastro de pessoa jur\u00eddica \u00e9 muito importante para quem est\u00e1 iniciando e pretende expandir seus neg\u00f3cios. Esse cadastro permite regularizar a situa\u00e7\u00e3o da empresa, o que abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens.<\/p>\n<p style=\"font-weight: 400;\">Por\u00e9m, h\u00e1 muito mais questionamentos sobre o que essa possibilidade realmente permite, quem pode usar e como. Portanto, pensando nisso, preparamos este conte\u00fado para mostrar aos novos empreendedores a import\u00e2ncia de comprar com CNPJ de forma simples e direta.<\/p>\n<h2>Como funciona comprar com CNPJ?<\/h2>\n<p style=\"font-weight: 400;\">Para comprar com CNPJ, a empresa deve primeiro estar devidamente legalizada, com seu registro e impostos em dia. Comprando desta forma, muitas empresas consultam o Cadastro Nacional de Economia antes de vender para outras.<\/p>\n<p style=\"font-weight: 400;\">\u00c9 importante na compra de itens com o CNPJ da empresa considerar apenas aqueles que fazem parte de sua infraestrutura (ex: m\u00f3veis para escrit\u00f3rio) e os que fazem parte da atividade comercial e s\u00e3o revendidos.<\/p>\n<p style=\"font-weight: 400;\">Isso porque cada tipo de mercadoria tem impostos e taxas diferentes. O que justamente leva as pessoas a comprarem itens que n\u00e3o correspondem ao seu cadastro. Por exemplo, quando o CNAE de uma empresa define ela pode comprar e vender objetos de tipo A, este objeto est\u00e1 sujeito \u00e0 regulamenta\u00e7\u00e3o da al\u00edquota x. Se a empresa violar esta regra, pode estar sujeita \u00e0 v\u00e1rios danos, incluindo a suspens\u00e3o permanente do CNPJ.<\/p>\n<h2>Compras no Atacado<\/h2>\n<p style=\"font-weight: 400;\">A principal vantagem de comprar pelo CNPJ \u00e9 o acesso a pre\u00e7os e condi\u00e7\u00f5es de atacado. Basicamente se trata de comprar produtos para revenda a pre\u00e7os mais baixos do que no varejo (para o consumidor final).<\/p>\n<p style=\"font-weight: 400;\">Portanto, a negocia\u00e7\u00e3o com fornecedores \u00e9 extremamente importante para conseguir pre\u00e7os mais competitivos na coleta ou compra de insumos. Comprar no CNPJ abre um amplo leque de oportunidades nesse quesito. Muitos fornecedores possuem condi\u00e7\u00f5es diferenciadas em rela\u00e7\u00e3o \u00e0s vendas no varejo e no atacado para pessoas jur\u00eddicas. Assim, ser\u00e1 mais f\u00e1cil conseguir maiores descontos.<\/p>\n<h2>Um nome limpo ajuda na hora de solicitar cr\u00e9dito<\/h2>\n<p style=\"font-weight: 400;\">Manter o CNPJ na atividade de compra sem penaliza\u00e7\u00f5es pode ajudar a solicitar empr\u00e9stimos de bancos que analisam esse hist\u00f3rico para saber se \u00e9 arriscado ou n\u00e3o oferecer capital ao empres\u00e1rio que est\u00e1 solicitando.<\/p>\n<p style=\"font-weight: 400;\">Portanto, o conselho n\u00famero um \u00e9 manter o bom nome da sua organiza\u00e7\u00e3o, lembre-se de que tamb\u00e9m h\u00e1 registros de maus pagadores no CNPJ. Portanto, tenha cuidado ao come\u00e7ar a comprar no CNPJ.<\/p>\n<p style=\"font-weight: 400;\">Como mencionei anteriormente, se existir um hist\u00f3rico de pagamentos em atraso, isso pode significar que voc\u00ea n\u00e3o conseguir\u00e1 negociar compras a cr\u00e9dito com fornecedores ou obter empr\u00e9stimos banc\u00e1rios. \u00c9 t\u00e3o f\u00e1cil evitar complica\u00e7\u00f5es quanto enfrent\u00e1-las.<\/p>\n<p style=\"font-weight: 400;\">N\u00e3o se esque\u00e7a que com pre\u00e7os de atacado muito mais baratos, \u00e9 natural ficar tentado a fazer compras pessoais. Aconselho voc\u00ea a n\u00e3o se deixar levar por essa tenta\u00e7\u00e3o &#8211; ela pode abrir precedentes perigosos para a sa\u00fade financeira de sua organiza\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400;\">\u00c9 extremamente importante separar as atividades de compras pessoais das profissionais para evitar contrair d\u00edvidas ou impactar o fluxo de caixa ao pagar d\u00edvidas n\u00e3o comerciais.<\/p>\n<h2>Vantagens adicionais de comprar com CNPJ<\/h2>\n<p style=\"font-weight: 400;\">Comprando de fornecedores pelo CNPJ, fica mais f\u00e1cil conseguir descontos e condi\u00e7\u00f5es de pagamento vantajosas. Al\u00e9m disso, \u00e9 comum encontrar fornecedores que vendem tanto no atacado quanto no varejo, uma forma que pode facilitar ainda mais o checkout do seu neg\u00f3cio.<\/p>\n<p style=\"font-weight: 400;\">O microempreendedor individual tamb\u00e9m pode utilizar o CNPJ para comprar alguns bens que facilitam o dia a dia do neg\u00f3cio. O carro \u00e9 um exemplo disso. O MEI pode comprar um ve\u00edculo com at\u00e9 30% de desconto no CNPJ.<\/p>\n<p style=\"font-weight: 400;\">Isso porque o microempreendedor fica isento de IPI e ICMS. O valor do desconto varia de acordo com o modelo e marca do carro negociado. \u00c9 necess\u00e1rio apresentar a certid\u00e3o de MEI, matr\u00edcula estadual atual e alguns outros documentos. O carro ent\u00e3o ser\u00e1 vinculado \u00e0 matr\u00edcula do MEI, portanto, pode evitar pagar muitos impostos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ter um cadastro de pessoa jur\u00eddica \u00e9 muito importante para quem est\u00e1 iniciando e pretende expandir seus neg\u00f3cios. Esse cadastro permite regularizar a situa\u00e7\u00e3o da empresa, o que abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Por\u00e9m, h\u00e1 muito mais questionamentos sobre o que essa possibilidade realmente permite, quem pode [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3507","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veja as Vantagens de Comprar com CNPJ - Ecoss Contabilidade<\/title>\n<meta name=\"description\" content=\"O cadastro no CNPJ abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Saiba mais!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veja as Vantagens de Comprar com CNPJ - Ecoss Contabilidade\" \/>\n<meta property=\"og:description\" content=\"O cadastro no CNPJ abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Saiba mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecoss Contabilidade\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-25T17:57:01+00:00\" \/>\n<meta name=\"author\" content=\"fabianadavi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fabianadavi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/\"},\"author\":{\"name\":\"fabianadavi\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#\\\/schema\\\/person\\\/c07ac252e57df449748fe0c9da4aaa5c\"},\"headline\":\"Veja as Vantagens de Comprar com CNPJ\",\"datePublished\":\"2023-01-25T17:57:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/\"},\"wordCount\":693,\"publisher\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#organization\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/\",\"url\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/\",\"name\":\"Veja as Vantagens de Comprar com CNPJ - Ecoss Contabilidade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#website\"},\"datePublished\":\"2023-01-25T17:57:01+00:00\",\"description\":\"O cadastro no CNPJ abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Saiba mais!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/2023\\\/01\\\/25\\\/veja-as-vantagens-de-comprar-com-cnpj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veja as Vantagens de Comprar com CNPJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#website\",\"url\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/\",\"name\":\"Ecoss Contabilidade\",\"description\":\"Contabilidade no Rio de Janeiro\",\"publisher\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#organization\",\"name\":\"Ecoss Contabilidade\",\"url\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/wp-content\\\/uploads\\\/sites\\\/73\\\/2024\\\/11\\\/cropped-ecoss-logo-1-hor-black-e1732704723668.png\",\"contentUrl\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/wp-content\\\/uploads\\\/sites\\\/73\\\/2024\\\/11\\\/cropped-ecoss-logo-1-hor-black-e1732704723668.png\",\"width\":1000,\"height\":285,\"caption\":\"Ecoss Contabilidade\"},\"image\":{\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/#\\\/schema\\\/person\\\/c07ac252e57df449748fe0c9da4aaa5c\",\"name\":\"fabianadavi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a484d2e6164d7a85269264dbf96ceb9aaff8e490c5e2f619ebf4a4e2eaeee27?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a484d2e6164d7a85269264dbf96ceb9aaff8e490c5e2f619ebf4a4e2eaeee27?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a484d2e6164d7a85269264dbf96ceb9aaff8e490c5e2f619ebf4a4e2eaeee27?s=96&d=mm&r=g\",\"caption\":\"fabianadavi\"},\"url\":\"https:\\\/\\\/rede4.contabilit.com.br\\\/ecoss\\\/author\\\/fabianadavi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veja as Vantagens de Comprar com CNPJ - Ecoss Contabilidade","description":"O cadastro no CNPJ abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Saiba mais!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Veja as Vantagens de Comprar com CNPJ - Ecoss Contabilidade","og_description":"O cadastro no CNPJ abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Saiba mais!","og_url":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/","og_site_name":"Ecoss Contabilidade","article_published_time":"2023-01-25T17:57:01+00:00","author":"fabianadavi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fabianadavi","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/#article","isPartOf":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/"},"author":{"name":"fabianadavi","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#\/schema\/person\/c07ac252e57df449748fe0c9da4aaa5c"},"headline":"Veja as Vantagens de Comprar com CNPJ","datePublished":"2023-01-25T17:57:01+00:00","mainEntityOfPage":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/"},"wordCount":693,"publisher":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#organization"},"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/","url":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/","name":"Veja as Vantagens de Comprar com CNPJ - Ecoss Contabilidade","isPartOf":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#website"},"datePublished":"2023-01-25T17:57:01+00:00","description":"O cadastro no CNPJ abre portas para o crescimento dos neg\u00f3cios. Comprar com CNPJ tem muitas vantagens. Saiba mais!","breadcrumb":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/2023\/01\/25\/veja-as-vantagens-de-comprar-com-cnpj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/rede4.contabilit.com.br\/ecoss\/"},{"@type":"ListItem","position":2,"name":"Veja as Vantagens de Comprar com CNPJ"}]},{"@type":"WebSite","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#website","url":"https:\/\/rede4.contabilit.com.br\/ecoss\/","name":"Ecoss Contabilidade","description":"Contabilidade no Rio de Janeiro","publisher":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rede4.contabilit.com.br\/ecoss\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#organization","name":"Ecoss Contabilidade","url":"https:\/\/rede4.contabilit.com.br\/ecoss\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#\/schema\/logo\/image\/","url":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-content\/uploads\/sites\/73\/2024\/11\/cropped-ecoss-logo-1-hor-black-e1732704723668.png","contentUrl":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-content\/uploads\/sites\/73\/2024\/11\/cropped-ecoss-logo-1-hor-black-e1732704723668.png","width":1000,"height":285,"caption":"Ecoss Contabilidade"},"image":{"@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rede4.contabilit.com.br\/ecoss\/#\/schema\/person\/c07ac252e57df449748fe0c9da4aaa5c","name":"fabianadavi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0a484d2e6164d7a85269264dbf96ceb9aaff8e490c5e2f619ebf4a4e2eaeee27?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a484d2e6164d7a85269264dbf96ceb9aaff8e490c5e2f619ebf4a4e2eaeee27?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a484d2e6164d7a85269264dbf96ceb9aaff8e490c5e2f619ebf4a4e2eaeee27?s=96&d=mm&r=g","caption":"fabianadavi"},"url":"https:\/\/rede4.contabilit.com.br\/ecoss\/author\/fabianadavi\/"}]}},"_links":{"self":[{"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/posts\/3507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/comments?post=3507"}],"version-history":[{"count":0,"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/posts\/3507\/revisions"}],"wp:attachment":[{"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/media?parent=3507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/categories?post=3507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rede4.contabilit.com.br\/ecoss\/wp-json\/wp\/v2\/tags?post=3507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}